{"id":27,"date":"2009-03-30T15:18:49","date_gmt":"2009-03-30T13:18:49","guid":{"rendered":"http:\/\/www.lucameneghetti.it\/addestramento\/?page_id=27"},"modified":"2023-06-07T10:24:51","modified_gmt":"2023-06-07T08:24:51","slug":"dove-siamo","status":"publish","type":"page","link":"https:\/\/www.lucameneghetti.it\/addestramento\/dove-siamo\/","title":{"rendered":"Centro Addestramento Cani Lupus in Fabula"},"content":{"rendered":"<h2>Centro Addestramento Cani &#8211; Inzago<\/h2>\n<p>Cascina Pignone | 20065 Inzago (MI) | <a href=\"https:\/\/goo.gl\/maps\/4TZ8pTnHEcGyQJzAA\">Navigatore<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-size: medium;\">Ci trovi ad Inzago, a pochi passi da Milano e facilmente raggiungibile anche da Bergamo.<\/span><\/p>\n<p><strong>Indicazioni stradali:<\/strong><\/p>\n<p><span style=\"font-size: medium;\">Se utilizzi l\u2019autostrada A4, esci a Trezzo Sull\u2019Adda e segui le indicazioni per Inzago, prosegui fino alla rotonda del Centro Commerciale &#8220;Le Corti Lombarde&#8221;\u2026 \u00a0alla rotonda, prendi l&#8217;uscita per Basiano\/Masate, svolta alla prima strada a sinistra e prima del centro abitato di Cascina Pignone ci troverai&#8230;. mezzo ai prati!<\/span><\/p>\n<p><center><span style=\"font-size: medium;\">Se hai difficolt\u00e0 a trovarci non esitare a contattarci al numero 333.3146137 per avere le indicazioni stradali:<\/span><br \/>\n<img decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-3562\" src=\"https:\/\/www.lucameneghetti.it\/addestramento\/wp-content\/uploads\/2023\/06\/centro-addestramento-cani-inzago.png\" alt=\"centro-addestramento-cani\" width=\"758\" height=\"622\" srcset=\"https:\/\/www.lucameneghetti.it\/addestramento\/wp-content\/uploads\/2023\/06\/centro-addestramento-cani-inzago.png 974w, https:\/\/www.lucameneghetti.it\/addestramento\/wp-content\/uploads\/2023\/06\/centro-addestramento-cani-inzago-300x246.png 300w, https:\/\/www.lucameneghetti.it\/addestramento\/wp-content\/uploads\/2023\/06\/centro-addestramento-cani-inzago-768x630.png 768w\" sizes=\"(max-width: 758px) 100vw, 758px\" \/><br \/>\n<small>Visualizza <a style=\"color: #0000ff; text-align: left;\" href=\"https:\/\/goo.gl\/maps\/4TZ8pTnHEcGyQJzAA\">Centro Addestramento Cani &#8211; Lupus in Fabula &#8211; by Luca Meneghetti<\/a> in una mappa di dimensioni maggiori<\/small><\/center><\/p>\n<p>Il centro Adddestramento Cani \u00e8 vicino anche da Basiano, Masate, Bellinzago Lombardo, Gessate, Gorgonzola, Pozzo d&#8217;Adda, Cambiago, Vaprio d&#8217;Adda, Trezzano Rosa, Cassano d&#8217;Adda, Pozzuolo Martesana<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Centro Addestramento Cani &#8211; Inzago Cascina Pignone | 20065 Inzago (MI) | Navigatore &nbsp; &nbsp; Ci trovi ad Inzago, a pochi passi da Milano e facilmente raggiungibile anche da Bergamo. Indicazioni stradali: Se utilizzi l\u2019autostrada A4, esci a Trezzo Sull\u2019Adda e segui le indicazioni per Inzago, prosegui fino alla rotonda del Centro Commerciale &#8220;Le Corti&nbsp;&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":6,"comment_status":"open","ping_status":"open","template":"","meta":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.lucameneghetti.it\/addestramento\/wp-json\/wp\/v2\/pages\/27"}],"collection":[{"href":"https:\/\/www.lucameneghetti.it\/addestramento\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.lucameneghetti.it\/addestramento\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.lucameneghetti.it\/addestramento\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lucameneghetti.it\/addestramento\/wp-json\/wp\/v2\/comments?post=27"}],"version-history":[{"count":51,"href":"https:\/\/www.lucameneghetti.it\/addestramento\/wp-json\/wp\/v2\/pages\/27\/revisions"}],"predecessor-version":[{"id":3567,"href":"https:\/\/www.lucameneghetti.it\/addestramento\/wp-json\/wp\/v2\/pages\/27\/revisions\/3567"}],"wp:attachment":[{"href":"https:\/\/www.lucameneghetti.it\/addestramento\/wp-json\/wp\/v2\/media?parent=27"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}